{"id":578,"date":"2026-03-23T13:28:58","date_gmt":"2026-03-23T13:28:58","guid":{"rendered":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/?p=578"},"modified":"2026-05-06T12:29:31","modified_gmt":"2026-05-06T12:29:31","slug":"veroeffentlichung-in-der-badr-information-01-2026","status":"publish","type":"post","link":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/veroeffentlichung-in-der-badr-information-01-2026\/","title":{"rendered":"Ver\u00f6ffentlichung in der BADR-Information 01\/2026"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/04\/badk.png.webp\" alt=\"\"><\/p>\n<div>\n<div class=\"article-content\">\n<div class=\"container-fluid m-0 p-0\">\n<div class=\"article-intro col-xl-8 mx-auto\">\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p>Unser Partner, Dr. Martin Lange, widmet sich in seinem Aufsatz in der BADR-Information 01\/2026, S. 14-34, der h\u00f6chstrichterlichen Rechtsprechung des Jahres 2025 zu verschiedenen Bereichen des Bankrechts. Dabei werden u.a. die Bereiche der Anlageberatung, der Prospekthaftung, der Erhebung von Verwahrentgelten, der Berechtigung von Vorf\u00e4lligkeitsentsch\u00e4digen bei Immobiliarverbraucherdarlehen, die Rechtsprechung des Bundesgerichtshofes zu Pr\u00e4miensparvertr\u00e4gen sowie zur Widerruflichkeit von Darlehen sowie die Frage der K\u00fcndigung von Zahlungsdiensterahmenvertr\u00e4gen im Zusammenhang mit Geldw\u00e4sche besprochen. Schlie\u00dflich erfolgt eine Darstellung der wesentlichen weiteren Entwicklung in der Rechtsprechung zu Betrugsf\u00e4llen im Zahlungsverkehr beim Online-Banking sowie zu Fragen der fristgem\u00e4\u00dfen Inanspruchnahme eines Kreditinstitutes aus einer B\u00fcrgschaft. Wie schon in 2025 festzustellen war, war auch das vergangene Jahr 2025 von einer erheblichen Zunahme von Klageverfahren in diesem Bereich gepr\u00e4gt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field--name-field-page-content field--type-entity-reference-revisions field--label-hidden field__items\">\n<div class=\"paragraph paragraph--type--container-one-column paragraph--view-mode--default background-white padding-0 gradient-0 spacing-bottom-1\">\n<div class=\"container-gradient container-gradient-1\"><\/div>\n<div class=\"container-gradient container-gradient-2\"><\/div>\n<p><a id=\"\" name=\"\" class=\"anchor\"><\/a><\/p>\n<div class=\"container-fluid\">\n<div class=\"row\" data-sticky-container=\"\">\n<div class=\"col-xl-10 mx-auto\">\n<div class=\"field field--name-field-content-left field--type-entity-reference-revisions field--label-hidden field__items\">\n<div class=\"paragraph paragraph--type--lawyer-grid paragraph--view-mode--default\">\n<div class=\"field field--name-field-lawyers field--type-entity-reference field--label-hidden field__items row\">\n<div class=\"field__item col-12 col-sm-6 col-xl-4 mb-6 \">\n<article class=\"node node--type-lawyer node--view-mode-teaser mb-0 mb-lg-6\">\n<div>\n<div class=\"field field--name-field-teaser-media field--type-entity-reference field--label-hidden field__item\">\n<article class=\"media media--type-image media--view-mode-lawyer-teaser\">\n<div class=\"blazy blazy--nojs blazy--field blazy--view blazy--field-image blazy--field-image--lawyer-teaser blazy--view--grueter-lawyer-list-block-block-1 blazy--view--grueter-lawyer-list blazy--view--grueter-lawyer-list--block-1 field field--name-field-image field--type-image field--label-hidden field__item\" data-blazy=\"\">\n<div data-b-thumb=\"\/sites\/default\/files\/styles\/person_teaser_375\/public\/images\/martin_lange_teaser_1920x2500px.jpg.webp?itok=ca_xEDBm\" data-b-ratios=\"{&quot;375&quot;:130.13,&quot;750&quot;:130.27}\" data-b-ratio=\"130.27\" data-b-token=\"b-555cea53378\" class=\"media media--blazy media--image media--responsive media--ratio media--ratio--fluid\"><picture><source srcset=\"\/sites\/default\/files\/styles\/person_teaser_375\/public\/images\/martin_lange_teaser_1920x2500px.jpg.webp?itok=ca_xEDBm 375w, \/sites\/default\/files\/styles\/person_teaser_750\/public\/images\/martin_lange_teaser_1920x2500px.jpg.webp?itok=7A4ZvIIY 750w\" type=\"image\/webp\" sizes=\"100vw\" width=\"750\" height=\"977\" \/><\/picture><\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2026\/04\/martin_lange_teaser_1920x2500px.jpg.webp\" alt=\"\"><\/p>\n<div>Rechtsanwalt<\/div>\n<div>\n<div class=\"field field--name-field-title-external field--type-string field--label-hidden field__item\">Dr. Martin Lange<\/div>\n<\/div>\n<p><a href=\"\/index.php\/anwaeltinnen-anwaelte\/dr-till-veltmann\/\">Read more<\/a><\/p>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"class\":\"section-head-blur-white nogrey bild-verlaeufe\",\"height\":\"pixels\",\"height_viewport\":600,\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"panel\",\"props\":{\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin\":\"default\",\"margin_remove_bottom\":false,\"margin_remove_top\":false,\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"position\":\"relative\",\"position_top\":\"70\",\"title_align\":\"top\",\"title_element\":\"h3\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"title\":{\"arguments\":{\"separator\":\", \",\"show_link\":false,\"link_style\":\"\"},\"name\":\"categoryString\"}}}},{\"type\":\"headline\",\"props\":{\"margin_remove_top\":true,\"position\":\"relative\",\"position_top\":\"70\",\"text_align\":\"center\",\"title_element\":\"h1\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"name\":\"title\"}}}},{\"type\":\"text\",\"props\":{\"class\":\"aktuelles_beitrag_datum\",\"column_breakpoint\":\"m\",\"margin\":\"medium\"},\"source\":{\"query\":{\"name\":\"posts.singlePost\"},\"props\":{\"content\":{\"filters\":{\"date\":\"d. F Y\"},\"name\":\"date\"}}}}]}]}],\"name\":\"Section: Headerbereich\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2026\\\/04\\\/badk.png.webp\",\"image_svg_color\":\"emphasis\",\"margin\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<div class=\\\"article-content\\\">\\n\n\n<div class=\\\"container-fluid m-0 p-0\\\">\\n\n\n<div class=\\\"article-intro col-xl-8 mx-auto\\\">\\n\n\n<div class=\\\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\\\">\\n\n\n<p>Unser Partner, Dr. Martin Lange, widmet sich in seinem Aufsatz in der BADR-Information 01\\\/2026, S. 14-34, der h\\u00f6chstrichterlichen Rechtsprechung des Jahres 2025 zu verschiedenen Bereichen des Bankrechts. Dabei werden u.a. die Bereiche der Anlageberatung, der Prospekthaftung, der Erhebung von Verwahrentgelten, der Berechtigung von Vorf\\u00e4lligkeitsentsch\\u00e4digen bei Immobiliarverbraucherdarlehen, die Rechtsprechung des Bundesgerichtshofes zu Pr\\u00e4miensparvertr\\u00e4gen sowie zur Widerruflichkeit von Darlehen sowie die Frage der K\\u00fcndigung von Zahlungsdiensterahmenvertr\\u00e4gen im Zusammenhang mit Geldw\\u00e4sche besprochen. Schlie\\u00dflich erfolgt eine Darstellung der wesentlichen weiteren Entwicklung in der Rechtsprechung zu Betrugsf\\u00e4llen im Zahlungsverkehr beim Online-Banking sowie zu Fragen der fristgem\\u00e4\\u00dfen Inanspruchnahme eines Kreditinstitutes aus einer B\\u00fcrgschaft. Wie schon in 2025 festzustellen war, war auch das vergangene Jahr 2025 von einer erheblichen Zunahme von Klageverfahren in diesem Bereich gepr\\u00e4gt.<\\\/p>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n\n\n<div class=\\\"field field--name-field-page-content field--type-entity-reference-revisions field--label-hidden field__items\\\">\\n\n\n<div class=\\\"paragraph paragraph--type--container-one-column paragraph--view-mode--default background-white padding-0 gradient-0 spacing-bottom-1\\\">\\n\n\n<div class=\\\"container-gradient container-gradient-1\\\"><\\\/div>\\n\n\n<div class=\\\"container-gradient container-gradient-2\\\"><\\\/div>\\n<a id=\\\"\\\" name=\\\"\\\" class=\\\"anchor\\\"><\\\/a>\\n\n\n<div class=\\\"container-fluid\\\">\\n\n\n<div class=\\\"row\\\" data-sticky-container=\\\"\\\">\\n\n\n<div class=\\\"col-xl-10 mx-auto\\\">\\n\n\n<div class=\\\"field field--name-field-content-left field--type-entity-reference-revisions field--label-hidden field__items\\\">\\n\n\n<div class=\\\"paragraph paragraph--type--lawyer-grid paragraph--view-mode--default\\\">\\n\n\n<div class=\\\"field field--name-field-lawyers field--type-entity-reference field--label-hidden field__items row\\\">\\n\n\n<div class=\\\"field__item col-12 col-sm-6 col-xl-4 mb-6 \\\">\\n\n\n<article class=\\\"node node--type-lawyer node--view-mode-teaser mb-0 mb-lg-6\\\">\\n\n\n<div>\\n\n\n<div class=\\\"field field--name-field-teaser-media field--type-entity-reference field--label-hidden field__item\\\">\\n\n\n<article class=\\\"media media--type-image media--view-mode-lawyer-teaser\\\">\\n\n\n<div class=\\\"blazy blazy--nojs blazy--field blazy--view blazy--field-image blazy--field-image--lawyer-teaser blazy--view--grueter-lawyer-list-block-block-1 blazy--view--grueter-lawyer-list blazy--view--grueter-lawyer-list--block-1 field field--name-field-image field--type-image field--label-hidden field__item\\\" data-blazy=\\\"\\\">\\n\n\n<div data-b-thumb=\\\"\\\/sites\\\/default\\\/files\\\/styles\\\/person_teaser_375\\\/public\\\/images\\\/martin_lange_teaser_1920x2500px.jpg.webp?itok=ca_xEDBm\\\" data-b-ratios=\\\"{&quot;375&quot;:130.13,&quot;750&quot;:130.27}\\\" data-b-ratio=\\\"130.27\\\" data-b-token=\\\"b-555cea53378\\\" class=\\\"media media--blazy media--image media--responsive media--ratio media--ratio--fluid\\\"><picture><source srcset=\\\"\\\/sites\\\/default\\\/files\\\/styles\\\/person_teaser_375\\\/public\\\/images\\\/martin_lange_teaser_1920x2500px.jpg.webp?itok=ca_xEDBm 375w, \\\/sites\\\/default\\\/files\\\/styles\\\/person_teaser_750\\\/public\\\/images\\\/martin_lange_teaser_1920x2500px.jpg.webp?itok=7A4ZvIIY 750w\\\" type=\\\"image\\\/webp\\\" sizes=\\\"100vw\\\" width=\\\"750\\\" height=\\\"977\\\" \\\/><\\\/picture><\\\/div>\\n<\\\/div>\\n<\\\/article>\\n<\\\/div>\\n<\\\/div>\\n<\\\/article>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\\n<\\\/div>\",\"margin\":\"default\"}}]}]},{\"type\":\"row\",\"props\":{\"class\":\"aktuelles_ansprechperson_grid\",\"layout\":\"1-3,1-3,1-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"panel\",\"props\":{\"class\":\"aktuelles_ansprechperson\",\"content\":\"\n\n<div class=\\\"field field--name-field-title-external field--type-string field--label-hidden field__item\\\">Dr. Martin Lange<\\\/div>\",\"content_column_breakpoint\":\"m\",\"icon_width\":80,\"image\":\"wp-content\\\/uploads\\\/2026\\\/04\\\/martin_lange_teaser_1920x2500px.jpg.webp\",\"image_align\":\"top\",\"image_box_decoration\":\"default\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link\":\"index.php\\\/anwaeltinnen-anwaelte\\\/dr-till-veltmann\\\/\",\"link_style\":\"default\",\"link_text\":\"Read more\",\"margin\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"panel_link\":true,\"title\":\"Rechtsanwalt\",\"title_align\":\"top\",\"title_element\":\"div\",\"title_grid_breakpoint\":\"m\",\"title_grid_width\":\"1-2\",\"title_hover_style\":\"reset\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"}},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"}}]}]}],\"version\":\"4.5.19\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Partner, Dr. Martin Lange, widmet sich in seinem Aufsatz in der BADR-Information 01\/2026, S. 14-34, der h\u00f6chstrichterlichen Rechtsprechung des Jahres 2025 zu verschiedenen Bereichen des Bankrechts.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-578","post","type-post","status-publish","format-standard","hentry","category-fach-news"],"_links":{"self":[{"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/posts\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":10,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/posts\/578\/revisions"}],"predecessor-version":[{"id":2491,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/posts\/578\/revisions\/2491"}],"wp:attachment":[{"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/media?parent=578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/categories?post=578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecstatic-raman.82-165-76-74.plesk.page\/en\/wp-json\/wp\/v2\/tags?post=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}